{"id":13711,"date":"2026-02-05T17:47:15","date_gmt":"2026-02-05T16:47:15","guid":{"rendered":"https:\/\/wordpress-i0skoccoc8cks40gw4gsw40g.coolify.develon.com\/?page_id=13711"},"modified":"2026-05-05T16:52:51","modified_gmt":"2026-05-05T14:52:51","slug":"bildungs-und-forschungseinrichtungen","status":"publish","type":"page","link":"https:\/\/www.hbenchmark.com\/de\/network\/enti-di-formazione-e-ricerca\/","title":{"rendered":"Bildungs- und Forschungseinrichtungen"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"13711\" class=\"elementor elementor-13711\">\n\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-27036e1f elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"27036e1f\" data-element_type=\"section\" data-e-type=\"section\" id=\"about\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7700a70d pxl-column-none\" data-id=\"7700a70d\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                                <div class=\"elementor-background-overlay\"><\/div>\r\n         \r\n        \t\t<div class=\"elementor-element elementor-element-37a9d5d4 elementor-widget__width-auto elementor-widget elementor-widget-pxl_breadcrumb\" data-id=\"37a9d5d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-breadcrumb-wrap\">\r\n\t<ul class=\"pxl-breadcrumb\"><li><span class=\"breadcrumb-entry\">Home<\/span><\/li><\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a191ec elementor-widget__width-inherit elementor-widget-laptop__width-initial elementor-widget elementor-widget-pxl_heading\" data-id=\"45a191ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-45a191ec-7121\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h2 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tWenn Daten zu Wissen werden, im Klassenzimmer und in der Forschung\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h2>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-507e5737 elementor-widget-laptop__width-initial elementor-widget elementor-widget-pxl_text_editor\" data-id=\"507e5737\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\t\t<p>Eine einzige Datenquelle: real, fortlaufend, zertifizierbar und reich an Einblicken in das Verhalten der touristischen Nachfrage. Ein Werkzeug, das die Qualit\u00e4t der Lehre erh\u00f6ht, Forschungsprojekte f\u00f6rdert und zukunftsorientierte Ausbildungsprogramme f\u00fcr den Tourismus festigt.<\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2634f96b elementor-widget elementor-widget-spacer\" data-id=\"2634f96b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39469ed0 elementor-widget__width-auto elementor-widget elementor-widget-pxl_button\" data-id=\"39469ed0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_button-39469ed0-5876\" class=\"pxl-button pxl-atc-link wow PXLfadeInUp\" data-wow-delay=\"600ms\">\r\n    <a href=\"\/de\/buchen-sie-ihre-demo\/\" class=\"btn pxl-icon-active btn-block-inline  btn-default pxl-icon--left\">\r\n                    <span class=\"pxl--btn-icon\">\r\n                <i aria-hidden=\"true\" class=\"flaticon flaticon-chat\"><\/i>                            <\/span>\r\n                <span class=\"pxl--btn-text\" data-text=\"Parla con un Esperto\">\r\n            Sprechen Sie mit einem Experten        <\/span>\r\n    <\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d4c069a elementor-widget__width-auto elementor-widget elementor-widget-pxl_button\" data-id=\"3d4c069a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_button-3d4c069a-1741\" class=\"pxl-button pxl-atc-link wow PXLfadeInUp\" data-wow-delay=\"600ms\">\r\n    <a href=\"#scroll\" class=\"btn pxl-icon-active btn-block-inline  btn-default pxl-icon--right\">\r\n                    <span class=\"pxl--btn-icon\">\r\n                <i aria-hidden=\"true\" class=\"fal fa-long-arrow-down\"><\/i>                            <\/span>\r\n                <span class=\"pxl--btn-text\" data-text=\"Esplora\">\r\n            Erkunden        <\/span>\r\n    <\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d05be83 elementor-widget elementor-widget-spacer\" data-id=\"4d05be83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b7b73bb elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"6b7b73bb\" data-element_type=\"section\" data-e-type=\"section\" id=\"scroll\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-657761f2 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"657761f2\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-6c9e4eec elementor-widget elementor-widget-pxl_heading\" data-id=\"6c9e4eec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-6c9e4eec-6114\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tTourismus erkl\u00e4rt mit echten Daten: Ein entscheidender bildungs- und wissenschaftlicher Vorteil\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-100a46a5 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"100a46a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\t\t<p>In einer Branche, die oft durch aggregierte Statistiken oder Informationsverz\u00f6gerungen beschrieben wird, liefert HBenchmark Trainern und Forschern, was fehlte: lebendige, detaillierte, aktuelle und auf realen Transaktionen basierende Daten. <br \/>Dies erm\u00f6glicht den Aufbau von Lernpfaden, die st\u00e4rker an der Realit\u00e4t orientiert sind, solidere Forschungsergebnisse zu erzielen und neues Wissen zu generieren, das f\u00fcr Institutionen, Praktiker und Studenten n\u00fctzlich ist.<\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b460fc1 elementor-widget__width-auto elementor-widget elementor-widget-pxl_button\" data-id=\"7b460fc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_button-7b460fc1-1107\" class=\"pxl-button pxl-atc-link wow PXLfadeInUp\" data-wow-delay=\"500ms\">\r\n    <a href=\"\/de\/buchen-sie-ihre-demo\/\" class=\"btn pxl-icon-active btn-block-inline  btn-default pxl-icon--left\">\r\n                    <span class=\"pxl--btn-icon\">\r\n                <i aria-hidden=\"true\" class=\"fal fa-calendar\"><\/i>                            <\/span>\r\n                <span class=\"pxl--btn-text\" data-text=\"Prenota la tua Demo\">\r\n            Demo buchen        <\/span>\r\n    <\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30e3c59 elementor-widget__width-auto elementor-widget elementor-widget-pxl_button\" data-id=\"30e3c59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_button-30e3c59-2693\" class=\"pxl-button pxl-atc-link wow PXLfadeInUp\" data-wow-delay=\"500ms\">\r\n    <a href=\"\/de\/kontakte\/\" class=\"btn pxl-icon-active btn-block-inline  btn-text-underline pxl-icon--right\">\r\n                <span class=\"pxl--btn-text\" data-text=\"Collabora con noi\">\r\n            Arbeiten Sie mit uns zusammen        <\/span>\r\n    <\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-53298e1e elementor-hidden-tablet elementor-hidden-mobile pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"53298e1e\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-8f831d2 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-pxl_image\" data-id=\"8f831d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-8f831d2-6083\" class=\"pxl-image-single pxl-disable-parallax-sm   wow skewIn\" data-wow-delay=\"500ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n                \r\n                                <div class=\"pxl-item--bg bg-image\" style=\"background-image: url(https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/programmers-cooperating-brainstorming-at-informati-2026-01-08-22-51-59-utc-scaled-e1773758168233.jpg);\">\r\n                                            <\/div>\r\n                                <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-107c0abb elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"107c0abb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4409fb pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"4409fb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n                <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-57350c60 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"57350c60\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-21a33160 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"21a33160\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-68b134bf elementor-widget elementor-widget-pxl_counter\" data-id=\"68b134bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-counter pxl-counter1 style-2\" data-wow-delay=\"ms\">\r\n            <div class=\"pxl-counter--holder\">\r\n        <div class=\"pxl-counter--number\">\r\n            <span class=\"pxl-counter--prefix el-empty\"><\/span>\r\n            <span class=\"pxl-counter--value effect-default\" data-duration=\"2000\" data-startnumber=\"1\" data-endnumber=\"80\" data-to-value=\"80\" data-delimiter=\"\">1<\/span>\r\n                            <span class=\"pxl-counter--suffix\">%<\/span>\r\n                    <\/div>\r\n                    <div class=\"pxl-counter--title\">in mehr analytischer Tiefe als herk\u00f6mmliche Datens\u00e4tze. Granulare Daten nach Zeitraum, Kanal, Produkt, Herkunft.<\/div>\r\n            <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4282b628 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"4282b628\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-326e36c elementor-widget elementor-widget-pxl_counter\" data-id=\"326e36c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-counter pxl-counter1 style-2\" data-wow-delay=\"ms\">\r\n            <div class=\"pxl-counter--holder\">\r\n        <div class=\"pxl-counter--number\">\r\n            <span class=\"pxl-counter--prefix el-empty\"><\/span>\r\n            <span class=\"pxl-counter--value effect-default\" data-duration=\"2000\" data-startnumber=\"1\" data-endnumber=\"-60\" data-to-value=\"-60\" data-delimiter=\"\">1<\/span>\r\n                            <span class=\"pxl-counter--suffix\">%<\/span>\r\n                    <\/div>\r\n                    <div class=\"pxl-counter--title\">Zeit f\u00fcr die Datenerhebung und -bereinigung. Strukturiert, homogen und verifiziert.<\/div>\r\n            <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-37b391b1 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"37b391b1\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-423df5d8 elementor-widget elementor-widget-pxl_counter\" data-id=\"423df5d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-counter pxl-counter1 style-2\" data-wow-delay=\"ms\">\r\n            <div class=\"pxl-counter--holder\">\r\n        <div class=\"pxl-counter--number\">\r\n            <span class=\"pxl-counter--prefix el-empty\"><\/span>\r\n            <span class=\"pxl-counter--value effect-default\" data-duration=\"2000\" data-startnumber=\"1\" data-endnumber=\"40\" data-to-value=\"40\" data-delimiter=\"\">1<\/span>\r\n                            <span class=\"pxl-counter--suffix\">%<\/span>\r\n                    <\/div>\r\n                    <div class=\"pxl-counter--title\">Zus\u00e4tzlich zur Qualit\u00e4t von Lehr- und Forschungsprojekten. Keine unvollst\u00e4ndigen Simulationen oder historische Reihen mehr.<\/div>\r\n            <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-7521d05 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"7521d05\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74d3816 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"74d3816\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-51dc9b7 elementor-widget elementor-widget-pxl_heading\" data-id=\"51dc9b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-51dc9b7-3051\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"200ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tEntdecken Sie die gestarteten Ausbildungs- und Forschungsprojekte\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77ee847a elementor-widget elementor-widget-pxl_partner_carousel\" data-id=\"77ee847a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_partner_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-swiper-slider pxl-partner-carousel pxl-partner-carousel1\">\r\n        <div class=\"pxl-carousel-inner\">\r\n            <div class=\"pxl-swiper-container\" dir=\"ltr\" data-settings=\"{&quot;slide_direction&quot;:&quot;horizontal&quot;,&quot;slide_percolumn&quot;:1,&quot;slide_mode&quot;:&quot;slide&quot;,&quot;slides_to_show&quot;:6,&quot;slides_to_show_xxl&quot;:6,&quot;slides_to_show_lg&quot;:4,&quot;slides_to_show_md&quot;:3,&quot;slides_to_show_sm&quot;:2,&quot;slides_to_show_xs&quot;:2,&quot;slides_to_scroll&quot;:1,&quot;arrow&quot;:false,&quot;pagination&quot;:false,&quot;pagination_type&quot;:&quot;bullets&quot;,&quot;autoplay&quot;:true,&quot;pause_on_hover&quot;:false,&quot;pause_on_interaction&quot;:true,&quot;delay&quot;:1000,&quot;loop&quot;:true,&quot;speed&quot;:1500}\">\r\n                <div class=\"pxl-swiper-wrapper\">\r\n                                            <div class=\"pxl-swiper-slide\">\r\n                            <div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\r\n                                                                    <div class=\"pxl-item--logo\">\r\n                                        <a href=\"#\">\r\n                                            <img decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/its_academy_turismo_veneto_logo.png\" width=\"284\" height=\"120\" alt=\"its_academy_turismo_veneto_logo\" title=\"its_academy_turismo_veneto_logo\" \/>                                            <img decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/its_academy_turismo_veneto_logo.png\" width=\"284\" height=\"120\" alt=\"its_academy_turismo_veneto_logo\" title=\"its_academy_turismo_veneto_logo\" \/>                                        <\/a>\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"pxl-swiper-slide\">\r\n                            <div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\r\n                                                                    <div class=\"pxl-item--logo\">\r\n                                        <a >\r\n                                            <img decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/supsi_logo.png\" width=\"284\" height=\"120\" alt=\"supsi_logo\" title=\"supsi_logo\" \/>                                            <img decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/supsi_logo.png\" width=\"284\" height=\"120\" alt=\"supsi_logo\" title=\"supsi_logo\" \/>                                        <\/a>\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"pxl-swiper-slide\">\r\n                            <div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\r\n                                                                    <div class=\"pxl-item--logo\">\r\n                                        <a >\r\n                                            <img decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/usi_logo.png\" width=\"284\" height=\"120\" alt=\"usi_logo\" title=\"usi_logo\" \/>                                            <img decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/usi_logo.png\" width=\"284\" height=\"120\" alt=\"usi_logo\" title=\"usi_logo\" \/>                                        <\/a>\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"pxl-swiper-slide\">\r\n                            <div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\r\n                                                                    <div class=\"pxl-item--logo\">\r\n                                        <a >\r\n                                            <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/iulm_logo-1.png\" width=\"284\" height=\"120\" alt=\"iulm_logo\" title=\"iulm_logo\" \/>                                            <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/iulm_logo-1.png\" width=\"284\" height=\"120\" alt=\"iulm_logo\" title=\"iulm_logo\" \/>                                        <\/a>\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"pxl-swiper-slide\">\r\n                            <div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\r\n                                                                    <div class=\"pxl-item--logo\">\r\n                                        <a >\r\n                                            <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/polimi_logo_osservatori.png\" width=\"284\" height=\"120\" alt=\"polimi_logo_osservatori\" title=\"polimi_logo_osservatori\" \/>                                            <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/polimi_logo_osservatori.png\" width=\"284\" height=\"120\" alt=\"polimi_logo_osservatori\" title=\"polimi_logo_osservatori\" \/>                                        <\/a>\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"pxl-swiper-slide\">\r\n                            <div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\r\n                                                                    <div class=\"pxl-item--logo\">\r\n                                        <a >\r\n                                            <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/its_turismo_marche.png\" width=\"284\" height=\"120\" alt=\"its_turismo_marche\" title=\"its_turismo_marche\" \/>                                            <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/its_turismo_marche.png\" width=\"284\" height=\"120\" alt=\"its_turismo_marche\" title=\"its_turismo_marche\" \/>                                        <\/a>\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"pxl-swiper-slide\">\r\n                            <div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\r\n                                                                    <div class=\"pxl-item--logo\">\r\n                                        <a >\r\n                                            <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/sssat_logo.png\" width=\"284\" height=\"120\" alt=\"sssat_logo\" title=\"sssat_logo\" \/>                                            <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/sssat_logo.png\" width=\"284\" height=\"120\" alt=\"sssat_logo\" title=\"sssat_logo\" \/>                                        <\/a>\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                        <\/div>\r\n                                    <\/div>\r\n            <\/div>\r\n\r\n            \r\n            \r\n        <\/div>\r\n    <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f876703 elementor-widget elementor-widget-image\" data-id=\"f876703\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.raiscuola.rai.it\/amp\/orientamento\/articoli\/2021\/11\/ITS-tecnico-superiore-per-Ia-gestione-di-strutture-turistico--ricettive-5649730f-ba64-407d-a181-8c232d7eb736.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"458\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/video-rai-scuola-1024x458.png\" class=\"attachment-large size-large wp-image-18698\" alt=\"\" srcset=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/video-rai-scuola-1024x458.png 1024w, https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/video-rai-scuola-300x134.png 300w, https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/video-rai-scuola-768x344.png 768w, https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/video-rai-scuola-1536x687.png 1536w, https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/video-rai-scuola-2048x916.png 2048w, https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/video-rai-scuola-1170x523.png 1170w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-beed2f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"beed2f1\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-52a5343 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"52a5343\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-7fb1a21 elementor-widget elementor-widget-pxl_heading\" data-id=\"7fb1a21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-7fb1a21-6883\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tUniversit\u00e0 IULM\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47e7089 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"47e7089\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\t\t<p>Die eingegangene Partnerschaft mit der IULM Universit\u00e4t zielt darauf ab, Studierenden, die f\u00fcr den Masterstudiengang in Hospitality and Tourism Management und den Master MITH (International Tourism and Hospitality) eingeschrieben sind, die Nutzung der von der HBenchmark-Plattform angebotenen Datenanalysetools zu erm\u00f6glichen, um akademische Forschungsarbeiten zu den Themen Tourismus, Hospitality Management und Destinationsmanagement durchzuf\u00fchren.<\/p><p>\u00a0<\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b88d5c9 elementor-hidden-tablet elementor-hidden-mobile pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"b88d5c9\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-a56b9eb elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-pxl_image\" data-id=\"a56b9eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-a56b9eb-7664\" class=\"pxl-image-single pxl-disable-parallax-sm   wow skewIn\" data-wow-delay=\"500ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n                \r\n                                <div class=\"pxl-item--image\" data-parallax-value=\"\">\r\n                                                    <img loading=\"lazy\" decoding=\"async\" width=\"1117\" height=\"1117\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/iulm_img.jpg\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                                                    <\/div>\r\n                                <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-43fcbb8 e-flex e-con-boxed e-con e-parent\" data-id=\"43fcbb8\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-656f7ed elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"656f7ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a27640 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"3a27640\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-79e18bb pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"79e18bb\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-3f30e1a elementor-widget elementor-widget-pxl_heading\" data-id=\"3f30e1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-3f30e1a-8324\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tITS Academy Turismo Veneto\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36c31c4 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"36c31c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\t\t<p>Die Zusammenarbeit mit <strong>ITS Academy Turismo Veneto<\/strong> \u2014 Weiterbildungsgang im Tourismus nach dem Schulabschluss \u2014 integriert Datenkultur in die Lehrpl\u00e4ne der Standorte Jesolo, Abano, Bardolino und Belluno. Ziel ist die Ausbildung von Fachkr\u00e4ften im Tourismussektor, die in der Lage sind, Gesch\u00e4fts-, Marketing- und Investitionsstrategien auf der Grundlage genauer Analysen zu entwickeln.<\/p><p>Das Bildungsangebot gliedert sich in:<\/p><ul><li><strong>Hospitality Data Intelligence Modul (ca. 20 Stunden)<\/strong>: Drei Lektionen \u00fcber Logik und KPIs zur Umwandlung von Metriken in Managemententscheidungen und Chancen f\u00fcr Destinationen.<\/li><li><strong>Vertikale Lektionen zum Open-Air-Bereich<\/strong>: spezielle Tiefenanalysen, die in Zusammenarbeit mit Faita Federcamping durchgef\u00fchrt wurden.<\/li><\/ul><p>Die Lehrmethode wechselt <strong>Frontalunterricht<\/strong> a <strong>Werkstatt und interaktive Workshops<\/strong>, wo die Studierenden die HBenchmark-Plattformen konkret nutzen. Am Ende des Kurses erm\u00f6glicht das Bestehen einer Abschlusspr\u00fcfung den Erhalt des\u2019<b data-path-to-node=\"8\" data-index-in-node=\"81\">Nachweis grundlegender Kompetenzen in Hospitality Data Intelligence<\/b>ein konkreter und unverwechselbarer Mehrwert f\u00fcr Ihren Lebenslauf, um sich mit einem technisch versierten und marktorientierten Profil zu pr\u00e4sentieren.<\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-81111e0 elementor-hidden-tablet elementor-hidden-mobile pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"81111e0\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-7316d67 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-pxl_image\" data-id=\"7316d67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-7316d67-8540\" class=\"pxl-image-single pxl-disable-parallax-sm   wow skewIn\" data-wow-delay=\"500ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n                \r\n                                <div class=\"pxl-item--image\" data-parallax-value=\"\">\r\n                                                    <img loading=\"lazy\" decoding=\"async\" width=\"1117\" height=\"1117\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/its_academy_turismo_veneto_img.png\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                                                    <\/div>\r\n                                <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-2cdcaec3 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"2cdcaec3\" data-element_type=\"section\" data-e-type=\"section\">\n\n                            <div class=\"elementor-background-overlay\"><\/div>\n            \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5987840a pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"5987840a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-3dd0e6e4 elementor-widget-tablet_extra__width-inherit elementor-widget__width-inherit elementor-widget elementor-widget-pxl_testimonial_carousel\" data-id=\"3dd0e6e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_testimonial_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-swiper-slider pxl-testimonial-carousel pxl-testimonial-carousel1 style-2\" >\r\n        <div class=\"pxl-carousel-inner\">\r\n            <div class=\"pxl-swiper-container\" dir=\"ltr\" data-settings=\"{&quot;slide_direction&quot;:&quot;horizontal&quot;,&quot;slide_percolumn&quot;:1,&quot;slide_mode&quot;:&quot;slide&quot;,&quot;slides_to_show&quot;:1,&quot;slides_to_show_xxl&quot;:1,&quot;slides_to_show_lg&quot;:1,&quot;slides_to_show_md&quot;:1,&quot;slides_to_show_sm&quot;:1,&quot;slides_to_show_xs&quot;:1,&quot;slides_to_scroll&quot;:1,&quot;arrow&quot;:false,&quot;pagination&quot;:false,&quot;pagination_type&quot;:&quot;bullets&quot;,&quot;autoplay&quot;:false,&quot;pause_on_hover&quot;:false,&quot;pause_on_interaction&quot;:true,&quot;delay&quot;:5000,&quot;loop&quot;:false,&quot;speed&quot;:500}\">\r\n                <div class=\"pxl-swiper-wrapper\">\r\n                                            <div class=\"pxl-swiper-slide\">\r\n                            <div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\r\n                                <div class=\"pxl-item--desc el-empty\">\"Wir haben investiert, damit die Kursteilnehmer der ITS Academy Turismo Veneto wettbewerbsf\u00e4hig sind und in Unternehmen arbeiten k\u00f6nnen, nachdem sie die modernsten Analysemethoden durch das Lesen von Big Data gelernt haben. Es ist entscheidend, erfolgreiche Entscheidungen zu treffen, die stets datengesteuert sind, und das gesamte Marktpotenzial zu nutzen, auch das, was noch unbekannt ist, um so Antworten auf wissenschaftlicher Basis zu finden.\u2019<\/div>\r\n                                                                    <div class=\"pxl-item--divider\">\r\n                                    <\/div>\r\n                                                                <div class=\"pxl-item--holder pxl-item--flexnw\">\r\n                                                                            <div class=\"pxl-item--avatar pxl-mr-24\">\r\n                                            <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/schiavon-77x77.png\" width=\"77\" height=\"77\" alt=\"Schiavon\" title=\"Schiavon\" \/>                                        <\/div>\r\n                                                                        <div class=\"pxl-item--meta\">\r\n                                        <div class=\"pxl-item--header\">\r\n                                            <h5 class=\"pxl-item--title el-empty\">Massimiliano Schiavon<\/h5>\r\n                                            <div class=\"pxl-item--rating\">\r\n                                                                                            <\/div>\r\n                                        <\/div>\r\n                                        <div class=\"pxl-item--position el-empty\">Pr\u00e4sident der ITS Academy Turismo Veneto<\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n\r\n        \r\n        \r\n    <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-c410110 e-flex e-con-boxed e-con e-parent\" data-id=\"c410110\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-ddba243 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ddba243\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-28c2084 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"28c2084\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ec7774 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"7ec7774\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-1d0a4d7 elementor-widget elementor-widget-pxl_heading\" data-id=\"1d0a4d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-1d0a4d7-3776\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tUniversit\u00e0 della Svizzera italiana (USI)\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44fcb20 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"44fcb20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\t\t<p>Die HBenchmark-Plattform wurde vom Wirtschafts-Forschungsinstitut und der Universit\u00e4t der italienischen Schweiz als <strong>offizieller Mitarbeiter von O-Tur<\/strong>, das Tourismusobservatoire der Schweizer Region.<\/p><p>O-Tur erstellt unter ausschlie\u00dflicher Nutzung der von HBenchmark bereitgestellten grafischen und analytischen Werkzeuge regelm\u00e4\u00dfig Berichte und Infografiken \u00fcber die Entwicklung des Tourismusmarktes.<\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-76fe6f5 elementor-hidden-tablet elementor-hidden-mobile pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"76fe6f5\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-3473af0 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-pxl_image\" data-id=\"3473af0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-3473af0-9263\" class=\"pxl-image-single pxl-disable-parallax-sm   wow skewIn\" data-wow-delay=\"500ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n                \r\n                                <div class=\"pxl-item--image\" data-parallax-value=\"\">\r\n                                                    <img loading=\"lazy\" decoding=\"async\" width=\"1117\" height=\"1117\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/usi_img.jpg\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                                                    <\/div>\r\n                                <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-7f090b2 e-flex e-con-boxed e-con e-parent\" data-id=\"7f090b2\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-1419644 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1419644\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-d038559 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"d038559\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8c7f97b pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"8c7f97b\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-ec445fd elementor-widget elementor-widget-pxl_heading\" data-id=\"ec445fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-ec445fd-9265\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tBachelor of Science in Leisure Management (SUPSI)\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e1f9ed elementor-widget elementor-widget-pxl_text_editor\" data-id=\"9e1f9ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\t\t<p data-path-to-node=\"1\">Der <b data-path-to-node=\"1\" data-index-in-node=\"4\">Bachelor of Science in Leisure Management<\/b> von <b data-path-to-node=\"1\" data-index-in-node=\"52\">SUPSI (Fachhochschule der italienischen Schweiz)<\/b> arbeitet aktiv mit HBenchmark zusammen. Die SUPSI ist eine exzellente Institution, die wissenschaftliche Exzellenz mit territorialer angewandter Forschung verbindet. Die <a class=\"ng-star-inserted\" href=\"https:\/\/www.supsi.ch\/en\/bachelor-leisure-management\" target=\"_blank\" rel=\"noopener\">Bachelor of Science in Leisure Management<\/a> zielt darauf ab, technische, organisatorische und Managementkompetenzen zu entwickeln, um in den Sektoren Sport, Veranstaltungen, Kreativwirtschaft, Tourismus und Unterhaltung t\u00e4tig zu sein.<\/p><p data-path-to-node=\"2\">Der Studiengang zeichnet sich durch stark praxisorientierte Module und einen erfahrungsorientierten Ansatz aus, der Praktika und Feldprojekte beinhaltet. In diesem Zusammenhang manifestiert sich die Zusammenarbeit mit HBenchmark durch Erfahrungsberichte im H\u00f6rsaal, konkrete Projekte und Praktikumsm\u00f6glichkeiten, die es den Studierenden erm\u00f6glichen, die Anwendung der Plattform im Sektor zu verstehen und sich in einem etablierten Unternehmen der Tourismusbranche zu beweisen.<\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c284cc4 elementor-hidden-tablet elementor-hidden-mobile pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"c284cc4\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-1b29119 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-pxl_image\" data-id=\"1b29119\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-1b29119-6760\" class=\"pxl-image-single pxl-disable-parallax-sm   wow skewIn\" data-wow-delay=\"500ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n                \r\n                                <div class=\"pxl-item--image\" data-parallax-value=\"\">\r\n                                                    <img loading=\"lazy\" decoding=\"async\" width=\"1117\" height=\"1117\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/03\/supsi_img.jpg\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                                                    <\/div>\r\n                                <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-db3a990 e-flex e-con-boxed e-con e-parent\" data-id=\"db3a990\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-c7b3fc0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c7b3fc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-394b79b elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"394b79b\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-adba4e8 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"adba4e8\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-9ab840f elementor-widget elementor-widget-pxl_heading\" data-id=\"9ab840f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-9ab840f-6196\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tH\u00f6here Fachschule f\u00fcr Gastgewerbe und Tourismus\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6c420c elementor-widget elementor-widget-pxl_text_editor\" data-id=\"c6c420c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\t\t<p>Die Zusammenarbeit zwischen HBenchmark und der SSSAT Bellinzona, einer eidgen\u00f6ssisch anerkannten Institution des Kantons Tessin f\u00fcr die spezialisierte Ausbildung im Gastgewerbe und Tourismus, gliedert sich in Lehrveranstaltungen, die darauf abzielen, die Bedeutung der Datenintelligenz f\u00fcr den Sektor zu vermitteln.<\/p><p>W\u00e4hrend der Lektionen werden die Analysemethoden der Plattform vertieft, wobei gezeigt wird, wie die Datenerfassung zu einem strategischen Instrument f\u00fcr das Verst\u00e4ndnis von Marktdynamiken werden kann. Der Schulungspfad sieht einen st\u00e4ndigen Vergleich zwischen der technischen Vision von HBenchmark und der praktischen Anwendung von Ticino Turismo vor, der den Studierenden einen konkreten \u00dcberblick dar\u00fcber gibt, wie die DMO historische und prognostizierte statistische Str\u00f6me f\u00fcr das Management und die Planung des Territoriums nutzt.<\/p><p>Durch diese Synergie integriert die SSSAT fortschrittliche technologische L\u00f6sungen in ihren Lehrplan, sodass zuk\u00fcnftige Fachkr\u00e4fte Kompetenzen in der Dateninterpretation erwerben und den Wert des Informationsaustauschs f\u00fcr die Wettbewerbsf\u00e4higkeit und die Entwicklung des gesamten Reiseziels verstehen k\u00f6nnen.<\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a284233 elementor-hidden-tablet elementor-hidden-mobile pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"a284233\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-c702b7e elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-pxl_image\" data-id=\"c702b7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-c702b7e-4109\" class=\"pxl-image-single pxl-disable-parallax-sm   wow skewIn\" data-wow-delay=\"500ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n                \r\n                                <div class=\"pxl-item--image\" data-parallax-value=\"\">\r\n                                                    <img loading=\"lazy\" decoding=\"async\" width=\"1117\" height=\"1117\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/04\/SSSAT_img.jpg\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                                                    <\/div>\r\n                                <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-ee964bc e-flex e-con-boxed e-con e-parent\" data-id=\"ee964bc\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-b3d37bc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b3d37bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-9952820 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"9952820\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f6b306d pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"f6b306d\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-986a94e elementor-widget elementor-widget-pxl_heading\" data-id=\"986a94e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-986a94e-6412\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tTravel Innovation Observatory der School of Management des Politecnico di Milano\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eef048c elementor-widget elementor-widget-pxl_text_editor\" data-id=\"eef048c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\t\t<p><strong>HBenchmark unterst\u00fctzt die Forschung 2026 des Travel Innovation Observatory der School of Management des Politecnico di Milano.<\/strong><\/p><p>In einem sich rasant entwickelnden \u00d6kosystem entschl\u00fcsselt diese Forschungsarbeit die Chancen, die aus dem Zusammenspiel von technologischer Innovation und neuen Gesch\u00e4ftsmodellen entstehen. Das Spektrum reicht von der Hotellerie und Parahotellerie \u2013 mit einem vertikalen Fokus auf den Open-Air-Sektor \u2013 bis hin zur Analyse neuer Grenzen im Bereich Business Travel, K\u00fcnstliche Intelligenz und Nachhaltigkeit. Ziel ist es, Unternehmen und Entscheidungstr\u00e4gern einen verl\u00e4sslichen Kompass zu bieten, um sich in der Datenwelt zu orientieren und den laufenden Wandel bewusst zu gestalten.<\/p><p>F\u00fcr HBenchmark entspringt diese Zusammenarbeit einer gemeinsamen Vision: Ver\u00e4nderungen zu interpretieren, um die Zukunft der Branche zu steuern. Das Observatory als Partner zu unterst\u00fctzen bedeutet, zu einem fundierten Wissen beizutragen, das in Booklet-Reports, Workshops und gro\u00dfen \u00f6ffentlichen Kongressen Form annimmt.\n\nVon der Quantifizierung von Besucherstr\u00f6men bis hin zum Verst\u00e4ndnis neuer Reisegewohnheiten stellen wir unsere Data Intelligence in den Dienst der renommiertesten akademischen Forschung Italiens im Bereich der digitalen Innovation f\u00fcr die Reisebranche. Unser gemeinsames Ziel ist es, den Sektor bewusster, solider und wettbewerbsf\u00e4higer wachsen zu lassen.<\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f1b9229 elementor-hidden-tablet elementor-hidden-mobile pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"f1b9229\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-0ed5974 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-pxl_image\" data-id=\"0ed5974\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-0ed5974-7712\" class=\"pxl-image-single pxl-disable-parallax-sm   wow skewIn\" data-wow-delay=\"500ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n                \r\n                                <div class=\"pxl-item--image\" data-parallax-value=\"\">\r\n                                                    <img loading=\"lazy\" decoding=\"async\" width=\"1117\" height=\"1117\" src=\"https:\/\/www.hbenchmark.com\/wp-content\/uploads\/2026\/04\/polimi_osservatori_img.jpg\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                                                    <\/div>\r\n                                <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-41bf5fe2 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"41bf5fe2\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69bbc78 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"69bbc78\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-1330f969 elementor-widget elementor-widget-pxl_heading\" data-id=\"1330f969\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-1330f969-2742\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\t\t\t<div class=\"pxl-item--subtitle px-sub-title-default\" data-wow-delay=\"ms\">\r\n\t\t\t\t<span class=\"pxl-item--subtext\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"\">WARUM BENCHMARK<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/div>\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tWarum Sie uns f\u00fcr Ihre Ausbildungs- und Forschungseinrichtung w\u00e4hlen sollten\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f21587a elementor-widget elementor-widget-pxl_text_editor\" data-id=\"2f21587a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\t\t<p>Nicht nur eine Plattform, sondern ein Partner, der den Tourismus messbar, verst\u00e4ndlich und didaktisch effektiver macht und Projekte f\u00f6rdert, die reale Auswirkungen auf das Territorium und die neuen Generationen haben.<\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41ca17a6 elementor-widget elementor-widget-pxl_text_carousel\" data-id=\"41ca17a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n    <div class=\"pxl-swiper-slider pxl-text-carousel5\" >\r\n        <div class=\"pxl-carousel-inner\">\r\n            <div class=\"pxl-swiper-container\" dir=\"ltr\" data-settings=\"{&quot;slide_direction&quot;:&quot;horizontal&quot;,&quot;slide_percolumn&quot;:1,&quot;slide_mode&quot;:&quot;slide&quot;,&quot;slides_to_show&quot;:4,&quot;slides_to_show_xxl&quot;:4,&quot;slides_to_show_lg&quot;:2,&quot;slides_to_show_md&quot;:2,&quot;slides_to_show_sm&quot;:1,&quot;slides_to_show_xs&quot;:1,&quot;slides_to_scroll&quot;:1,&quot;arrow&quot;:false,&quot;pagination&quot;:false,&quot;pagination_type&quot;:&quot;progressbar&quot;,&quot;autoplay&quot;:true,&quot;pause_on_hover&quot;:false,&quot;pause_on_interaction&quot;:true,&quot;delay&quot;:5000,&quot;loop&quot;:false,&quot;speed&quot;:500}\">\r\n                <div class=\"pxl-swiper-wrapper\">\r\n                                            <div class=\"pxl-swiper-slide\">\r\n                            <div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"600ms\">\r\n                                <div class=\"pxl-item--icon\">\r\n                                                                            <i class=\"fal fa-check\"><\/i>\r\n                                                                    <\/div>\r\n                                <h3 class=\"pxl-item--title el-empty\">Praktische Lehre<\/h3>\r\n                                <p class=\"pxl-item--desc el-empty\">HBenchmark bringt echte Daten und konkrete F\u00e4lle in den Unterricht und macht die Ausbildung aktueller und marktorientierter.<\/p>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"pxl-swiper-slide\">\r\n                            <div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"600ms\">\r\n                                <div class=\"pxl-item--icon\">\r\n                                                                            <i class=\"fal fa-check\"><\/i>\r\n                                                                    <\/div>\r\n                                <h3 class=\"pxl-item--title el-empty\">Solide Forschung<\/h3>\r\n                                <p class=\"pxl-item--desc el-empty\">Vollst\u00e4ndige und aktuelle Datens\u00e4tze verbessern die Qualit\u00e4t von Studien und erm\u00f6glichen zuverl\u00e4ssigere quantitative Analysen.<\/p>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"pxl-swiper-slide\">\r\n                            <div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"600ms\">\r\n                                <div class=\"pxl-item--icon\">\r\n                                                                            <i class=\"fal fa-check\"><\/i>\r\n                                                                    <\/div>\r\n                                <h3 class=\"pxl-item--title el-empty\">Datenpflege<\/h3>\r\n                                <p class=\"pxl-item--desc el-empty\">Zur Verbreitung eines datengesteuerten Ansatzes im Tourismus beitragen, indem Wissen und Wert f\u00fcr das Territorium generiert werden.<\/p>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"pxl-swiper-slide\">\r\n                            <div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"600ms\">\r\n                                <div class=\"pxl-item--icon\">\r\n                                                                            <i class=\"fal fa-check\"><\/i>\r\n                                                                    <\/div>\r\n                                <h3 class=\"pxl-item--title el-empty\">Kollektives Wissen<\/h3>\r\n                                <p class=\"pxl-item--desc el-empty\">Die Zusammenarbeit mit HBenchmark bedeutet, die.<\/p>\r\n                            <\/div>\r\n                        <\/div>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n            <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ad6a31f elementor-widget elementor-widget-spacer\" data-id=\"7ad6a31f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cf78a6f elementor-widget__width-inherit elementor-align-center elementor-widget-laptop__width-initial elementor-align-center elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-pxl_button\" data-id=\"3cf78a6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_button-3cf78a6f-2855\" class=\"pxl-button pxl-atc-link wow PXLfadeInUp\" data-wow-delay=\"500ms\">\r\n    <a href=\"\/de\/buchen-sie-ihre-demo\/\" class=\"btn pxl-icon-active btn-block-inline  btn-default pxl-icon--left\">\r\n                    <span class=\"pxl--btn-icon\">\r\n                <i aria-hidden=\"true\" class=\"fal fa-calendar\"><\/i>                            <\/span>\r\n                <span class=\"pxl--btn-text\" data-text=\"Prenota la tua Demo\">\r\n            Demo buchen        <\/span>\r\n    <\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-2370a4af elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"2370a4af\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\n                            <div class=\"elementor-background-overlay\"><\/div>\n            \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-37d36d3c pxl-overflow-hidden pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"37d36d3c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n                <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-63878dca elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"63878dca\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-673f3ece pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"673f3ece\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-66d4901c elementor-widget elementor-widget-pxl_heading\" data-id=\"66d4901c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-66d4901c-8259\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\t\t\t<div class=\"pxl-item--subtitle px-sub-title-default wow PXLfadeInUp\" data-wow-delay=\"200ms\">\r\n\t\t\t\t<span class=\"pxl-item--subtext\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"\">ERFOLGSFALL<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/div>\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tLivigno: ein neues Modell des datengesteuerten Tourismus.\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95c9347 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"95c9347\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"400ms\">\r\n\t\t<p>\u00dcber 70% der \u00fcberwachten Aufnahmef\u00e4higkeit, t\u00e4gliche Aktualisierungen, 24 Monate Historie und 12 Monate Prognose: eine kontinuierliche und gemeinsame Erfassung des Gebiets.<\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d2297dc elementor-widget__width-auto elementor-widget elementor-widget-pxl_button\" data-id=\"6d2297dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_button-6d2297dc-9735\" class=\"pxl-button pxl-atc-link wow PXLfadeInUp\" data-wow-delay=\"500ms\">\r\n    <a href=\"#\" class=\"btn pxl-icon-active btn-block-inline  btn-default pxl-icon--right\">\r\n                    <span class=\"pxl--btn-icon\">\r\n                <i aria-hidden=\"true\" class=\"fal fa-long-arrow-right\"><\/i>                            <\/span>\r\n                <span class=\"pxl--btn-text\" data-text=\"Approfondisci\">\r\n            Vertiefe        <\/span>\r\n    <\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2bb54922 elementor-hidden-tablet elementor-hidden-mobile pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"2bb54922\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n                <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5894aef2 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"5894aef2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-301ccffe pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"301ccffe\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-601affb8 elementor-widget elementor-widget-pxl_counter\" data-id=\"601affb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-counter pxl-counter3 style-1 wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n    <div class=\"pxl-counter--holder\">\r\n                        <div class=\"pxl-counter--number shape-show\">\r\n            <span class=\"pxl-counter--prefix el-empty\"><\/span>\r\n            <span class=\"pxl-counter--value effect-slide\" data-duration=\"2000\" data-startnumber=\"1\" data-endnumber=\"8\" data-to-value=\"8\" data-delimiter=\"\">1<\/span>\r\n                            <span class=\"pxl-counter--suffix\">+<\/span>\r\n                    <\/div>\r\n                    <div class=\"pxl-counter--title\">Monate Sichtbarkeit auf die touristischen Str\u00f6me.<\/div>\r\n            <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-700e6541 elementor-widget elementor-widget-pxl_counter\" data-id=\"700e6541\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-counter pxl-counter3 style-1 wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n    <div class=\"pxl-counter--holder\">\r\n                        <div class=\"pxl-counter--number shape-show\">\r\n            <span class=\"pxl-counter--prefix el-empty\"><\/span>\r\n            <span class=\"pxl-counter--value effect-slide\" data-duration=\"2000\" data-startnumber=\"1\" data-endnumber=\"6\" data-to-value=\"6\" data-delimiter=\"\">1<\/span>\r\n                            <span class=\"pxl-counter--suffix\">+<\/span>\r\n                    <\/div>\r\n                    <div class=\"pxl-counter--title\">Webinare zur Begleitung der Saison.<\/div>\r\n            <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54f55b9a elementor-widget elementor-widget-pxl_counter\" data-id=\"54f55b9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-counter pxl-counter3 style-1 wow PXLfadeInUp\" data-wow-delay=\"350ms\">\r\n    <div class=\"pxl-counter--holder\">\r\n                        <div class=\"pxl-counter--number shape-show\">\r\n            <span class=\"pxl-counter--prefix el-empty\"><\/span>\r\n            <span class=\"pxl-counter--value effect-slide\" data-duration=\"2000\" data-startnumber=\"1\" data-endnumber=\"40\" data-to-value=\"40\" data-delimiter=\"\">1<\/span>\r\n                            <span class=\"pxl-counter--suffix\">%<\/span>\r\n                    <\/div>\r\n                    <div class=\"pxl-counter--title\">Verringerung der saisonalen Unsicherheit.<\/div>\r\n            <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-66cd7bf4 elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"66cd7bf4\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5578358a pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"5578358a\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-3ee21990 elementor-widget elementor-widget-pxl_heading\" data-id=\"3ee21990\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-3ee21990-5880\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\t\t\t<div class=\"pxl-item--subtitle px-sub-title-default\" data-wow-delay=\"ms\">\r\n\t\t\t\t<span class=\"pxl-item--subtext\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"\">HB AKADEMIE<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/div>\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"200ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tAufbau von Kompetenzen mit realen Daten.\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63f18e0a elementor-widget elementor-widget-pxl_text_editor\" data-id=\"63f18e0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" >\r\n\t\t<p>Die Ausbildungsprogramme der HB Academy sind darauf ausgelegt, Daten in operative Kompetenzen umzuwandeln. Programme, die f\u00fcr verschiedene Niveaus und Bed\u00fcrfnisse konzipiert sind, aber durch einen praktischen Ansatz, der auf realen Daten basiert, verbunden sind, um Methode, Entscheidungsautonomie und professionellen Wert zu entwickeln.<\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56fa013c post-layout-service-1 elementor-widget elementor-widget-pxl_post_carousel\" data-id=\"56fa013c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_post_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n    <div class=\"pxl-swiper-slider pxl-service-carousel pxl-service-carousel1 style-1\" >\r\n        <div class=\"pxl-carousel-inner\">\r\n\r\n            \r\n            <div class=\"pxl-swiper-container\" dir=\"ltr\" data-settings=\"{&quot;slide_direction&quot;:&quot;horizontal&quot;,&quot;slide_percolumn&quot;:1,&quot;slide_percolumnfill&quot;:1,&quot;slide_mode&quot;:&quot;slide&quot;,&quot;slides_to_show&quot;:2,&quot;slides_to_show_xxl&quot;:2,&quot;slides_to_show_lg&quot;:2,&quot;slides_to_show_md&quot;:2,&quot;slides_to_show_sm&quot;:2,&quot;slides_to_show_xs&quot;:1,&quot;slides_to_scroll&quot;:1,&quot;slides_gutter&quot;:30,&quot;arrow&quot;:false,&quot;pagination&quot;:false,&quot;pagination_type&quot;:&quot;bullets&quot;,&quot;autoplay&quot;:true,&quot;pause_on_hover&quot;:false,&quot;pause_on_interaction&quot;:true,&quot;delay&quot;:5000,&quot;loop&quot;:false,&quot;speed&quot;:500}\">\r\n                <div class=\"pxl-swiper-wrapper\">\r\n                                            <div class=\"pxl-swiper-slide\">\r\n                            <div class=\"pxl-post--inner\">\r\n                                <div class=\"pxl-post--header\">\r\n                                    <div class=\"pxl-post--icon\">\r\n                                                                                    <i class=\"fal fa-file-certificate\"><\/i>\r\n                                                                                                                    <\/div>\r\n\r\n                                    <span class=\"pxl-post--number\">\r\n                                                                                    01                                        .\r\n                                    <\/span>\r\n                                <\/div>\r\n                                <div class=\"pxl-post--holder\">\r\n                                    <h3 class=\"pxl-post--title\">\r\n                                        <a href=\"https:\/\/www.hbenchmark.com\/de\/prodotti-e-servizi\/d-benchmark-executive-training-program\/\">D-Benchmark Executive Training Programm<\/a>\r\n                                    <\/h3>\r\n                                                                            <div class=\"pxl-post--excerpt\">\r\n                                            Ein fortgeschrittener Ausbildungsweg f\u00fcr Destination Manager und Berater, die D-Benchmark-Daten bewusst und strategisch nutzen m\u00f6chten.                                        <\/div>\r\n                                                                        <div class=\"pxl-item--divider\"><\/div>\r\n                                                                            <div class=\"pxl-post--readmore\">\r\n                                            <a href=\"https:\/\/www.hbenchmark.com\/de\/prodotti-e-servizi\/d-benchmark-executive-training-program\/\">\r\n                                                Mehr erfahren                                                <i class=\"flaticon-right-arrow-long rtl-reverse\"><\/i>\r\n                                            <\/a>\r\n                                        <\/div>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"pxl-swiper-slide\">\r\n                            <div class=\"pxl-post--inner\">\r\n                                <div class=\"pxl-post--header\">\r\n                                    <div class=\"pxl-post--icon\">\r\n                                                                                    <i class=\"fal fa-file-certificate\"><\/i>\r\n                                                                                                                    <\/div>\r\n\r\n                                    <span class=\"pxl-post--number\">\r\n                                                                                    02                                        .\r\n                                    <\/span>\r\n                                <\/div>\r\n                                <div class=\"pxl-post--holder\">\r\n                                    <h3 class=\"pxl-post--title\">\r\n                                        <a href=\"https:\/\/www.hbenchmark.com\/de\/prodotti-e-servizi\/d-intelligence-executive-training-program\/\">D-Intelligence Executive Weiterbildungsprogramm<\/a>\r\n                                    <\/h3>\r\n                                                                            <div class=\"pxl-post--excerpt\">\r\n                                            Ein Executive-Programm, das Tourismusmanager und Entscheidungstr\u00e4ger dabei unterst\u00fctzt, reale Daten in strategische Entscheidungen umzuwandeln, basierend auf...                                        <\/div>\r\n                                                                        <div class=\"pxl-item--divider\"><\/div>\r\n                                                                            <div class=\"pxl-post--readmore\">\r\n                                            <a href=\"https:\/\/www.hbenchmark.com\/de\/prodotti-e-servizi\/d-intelligence-executive-training-program\/\">\r\n                                                Mehr erfahren                                                <i class=\"flaticon-right-arrow-long rtl-reverse\"><\/i>\r\n                                            <\/a>\r\n                                        <\/div>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"pxl-swiper-slide\">\r\n                            <div class=\"pxl-post--inner\">\r\n                                <div class=\"pxl-post--header\">\r\n                                    <div class=\"pxl-post--icon\">\r\n                                                                                    <i class=\"fal fa-file-certificate\"><\/i>\r\n                                                                                                                    <\/div>\r\n\r\n                                    <span class=\"pxl-post--number\">\r\n                                                                                    03                                        .\r\n                                    <\/span>\r\n                                <\/div>\r\n                                <div class=\"pxl-post--holder\">\r\n                                    <h3 class=\"pxl-post--title\">\r\n                                        <a href=\"https:\/\/www.hbenchmark.com\/de\/prodotti-e-servizi\/ho-benchmark-executive-training-program\/\">HO-Benchmark Executive Trainingsprogramm<\/a>\r\n                                    <\/h3>\r\n                                                                            <div class=\"pxl-post--excerpt\">\r\n                                            Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut...                                        <\/div>\r\n                                                                        <div class=\"pxl-item--divider\"><\/div>\r\n                                                                            <div class=\"pxl-post--readmore\">\r\n                                            <a href=\"https:\/\/www.hbenchmark.com\/de\/prodotti-e-servizi\/ho-benchmark-executive-training-program\/\">\r\n                                                Mehr erfahren                                                <i class=\"flaticon-right-arrow-long rtl-reverse\"><\/i>\r\n                                            <\/a>\r\n                                        <\/div>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                    <\/div>\r\n            <\/div>\r\n\r\n                    <\/div>\r\n    <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Home Quando il dato diventa conoscenza, in aula e nella ricerca Una fonte dati unica: reale, continua, certificabile e ricca di insight sul comportamento della domanda turistica. Uno strumento che eleva la qualit\u00e0 della didattica, alimenta progetti di ricerca e consolida percorsi formativi orientati al futuro del turismo. Parla con un Esperto Esplora Il turismo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":13705,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-13711","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.hbenchmark.com\/de\/wp-json\/wp\/v2\/pages\/13711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hbenchmark.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hbenchmark.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hbenchmark.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hbenchmark.com\/de\/wp-json\/wp\/v2\/comments?post=13711"}],"version-history":[{"count":196,"href":"https:\/\/www.hbenchmark.com\/de\/wp-json\/wp\/v2\/pages\/13711\/revisions"}],"predecessor-version":[{"id":27277,"href":"https:\/\/www.hbenchmark.com\/de\/wp-json\/wp\/v2\/pages\/13711\/revisions\/27277"}],"up":[{"embeddable":true,"href":"https:\/\/www.hbenchmark.com\/de\/wp-json\/wp\/v2\/pages\/13705"}],"wp:attachment":[{"href":"https:\/\/www.hbenchmark.com\/de\/wp-json\/wp\/v2\/media?parent=13711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}